{"id":9947,"date":"2025-11-21T14:05:38","date_gmt":"2025-11-21T13:05:38","guid":{"rendered":"https:\/\/nunzioalfonso.it\/?page_id=9947"},"modified":"2025-11-30T13:49:48","modified_gmt":"2025-11-30T12:49:48","slug":"termini-e-condizioni","status":"publish","type":"page","link":"https:\/\/nunzioalfonso.it\/en\/termini-e-condizioni\/","title":{"rendered":"Termini e Condizioni"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9947\" class=\"elementor elementor-9947\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91cfc45 e-flex e-con-boxed e-con e-parent\" data-id=\"91cfc45\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-bfb5013 elementor-widget elementor-widget-spacer\" data-id=\"bfb5013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00639a2 elementor-widget elementor-widget-spacer\" data-id=\"00639a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c7967 elementor-widget elementor-widget-text-editor\" data-id=\"34c7967\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>1. Identificazione del venditore<\/h3>\n<p data-path-to-node=\"8\">I beni oggetto delle presenti condizioni generali sono posti in vendita dalla societ\u00e0 <b>Nunzio Alfonso Srl<\/b>, con sede legale in Zona Industriale A.S.I. Giammoro, s.n. &#8211; 98042 Pace del Mela (ME), Italia &#8211; P. IVA: <b>03655770836<\/b><\/p>\n<p><!-- \/wp:list --><!-- wp:paragraph --><\/p>\n<hr \/>\n<h2><br \/>2. Oggetto del contratto<\/h2>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p data-path-to-node=\"11\">Le presenti Condizioni Generali hanno per oggetto l&#8217;acquisto di prodotti (stampi per blocchi in cemento e accessori) effettuato a distanza tramite rete telematica sul sito <i>nunzioalfonso.it.<\/i><\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<p><!-- wp:paragraph --><\/p>\n<h2>3. Procedura d&#8217;acquisto e conclusione del contratto<\/h2>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p data-path-to-node=\"16\">Il cliente pu\u00f2 acquistare i prodotti presenti nel catalogo elettronico inoltrando l&#8217;ordine tramite le procedure previste dal sito. Data la natura tecnica dei prodotti e la modalit\u00e0 di pagamento differito, l&#8217;invio dell&#8217;ordine da parte del cliente vale come <b>proposta contrattuale<\/b>. La ricezione dell&#8217;ordine non implica la conclusione automatica del contratto. Il contratto si intende concluso solo nel momento in cui:<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<ol>\n<li data-path-to-node=\"14,0,0\">Il Venditore contatta il Cliente per confermare la disponibilit\u00e0 e i dettagli tecnici.<\/li>\n<li data-path-to-node=\"14,1,0\">Il Cliente effettua il pagamento tramite Bonifico Bancario.<\/li>\n<li data-path-to-node=\"14,2,0\">Il Venditore riceve l&#8217;accredito e avvia la spedizione.<\/li>\n<\/ol>\n<hr \/>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<h2><br \/>4. Prezzi e Pagamenti<\/h2>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Tutti i prezzi di vendita dei prodotti esposti sul sito sono indicati in Euro (\u20ac). L&#8217;unica modalit\u00e0 di pagamento accettata \u00e8 il <b>Bonifico Bancario Anticipato<\/b>. Le coordinate bancarie (IBAN) verranno fornite al cliente tramite email o contatto telefonico successivamente all&#8217;invio dell&#8217;ordine.<\/p>\n<hr \/>\n<h2><br \/>5. Spedizioni e consegna<\/h2>\n<p>Le spedizioni sono <b>GRATUITE<\/b> su tutto il territorio italiano. La merce viaggia a rischio e pericolo del Venditore fino alla consegna al Cliente. Al momento della consegna, il Cliente \u00e8 tenuto a controllare l&#8217;integrit\u00e0 dell&#8217;imballaggio. Eventuali danni visibili devono essere immediatamente contestati al corriere apponendo la dicitura &#8220;ACCETTATO CON RISERVA&#8221;.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<hr \/>\n<h2><br \/>6. Diritto di recesso e resi<\/h2>\n<p>Il Cliente ha diritto di recedere dal contratto, senza alcuna penalit\u00e0 e senza specificarne il motivo, entro il termine di <b>20 giorni<\/b> (estensione volontaria rispetto ai 14 di legge) dal ricevimento della merce. Per i dettagli completi su come effettuare un reso e sulle condizioni di integrit\u00e0 del prodotto (che non deve essere stato usato con cemento\/oli\/ecc.), si rimanda alla pagina specifica <a href=\"https:\/\/nunzioalfonso.it\/en\/spedizioni-resi\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><b>Spedizioni e Resi<\/b><\/span>.<\/a><\/p>\n<hr \/>\n<h2><br \/>7. Garanzia legale di conformit\u00e0<\/h2>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p data-path-to-node=\"22\">Tutti i prodotti venduti sono coperti dalla Garanzia Legale di Conformit\u00e0:<\/p>\n<ul>\n<li data-path-to-node=\"23,0,0\"><b>Per i Consumatori privati:<\/b> Garanzia di 24 mesi per difetti di conformit\u00e0.<\/li>\n<li data-path-to-node=\"23,0,0\"><b>Per i Clienti con Partita IVA (Professionisti):<\/b> Garanzia di 12 mesi. Sono esclusi dalla garanzia i danni causati da normale usura, uso improprio (es. utilizzo di calcestruzzo non idoneo), mancata manutenzione o manomissione del prodotto.<\/li>\n<\/ul>\n<hr \/>\n<h2><br \/>8. Foro competente<\/h2>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p data-path-to-node=\"25\">Per le controversie civili inerenti all&#8217;applicazione delle presenti condizioni:<\/p>\n<ul>\n<li data-path-to-node=\"26,0,0\">Se il cliente \u00e8 un <b>Consumatore<\/b> (privato), la competenza territoriale \u00e8 quella del giudice del luogo di residenza o domicilio del consumatore.<\/li>\n<li data-path-to-node=\"26,0,0\">Se il cliente \u00e8 un <b>Professionista<\/b> (acquisto con Partita IVA), il foro competente esclusivo \u00e8 quello di <b>Messina<\/b>.<\/li>\n<\/ul>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67708b5 elementor-widget elementor-widget-spacer\" data-id=\"67708b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>1. Identificazione del venditore I beni oggetto delle presenti condizioni generali sono posti in vendita dalla societ\u00e0 Nunzio Alfonso Srl, con sede legale in Zona Industriale A.S.I. Giammoro, s.n. &#8211; 98042 Pace del Mela (ME), Italia &#8211; P. IVA: 03655770836 2. Oggetto del contratto Le presenti Condizioni Generali hanno per oggetto l&#8217;acquisto di prodotti (stampi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9947","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Termini e Condizioni - nunzioalfonso.it<\/title>\n<meta name=\"description\" content=\"Leggi le condizioni generali di vendita, le modalit\u00e0 di pagamento, la garanzia e i diritti di recesso per l&#039;acquisto su Nunzio Alfonso Srl.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nunzioalfonso.it\/en\/termini-e-condizioni\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Termini e Condizioni - nunzioalfonso.it\" \/>\n<meta property=\"og:description\" content=\"Leggi le condizioni generali di vendita, le modalit\u00e0 di pagamento, la garanzia e i diritti di recesso per l&#039;acquisto su Nunzio Alfonso Srl.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nunzioalfonso.it\/en\/termini-e-condizioni\/\" \/>\n<meta property=\"og:site_name\" content=\"nunzioalfonso.it\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-30T12:49:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nunzioalfonso.it\/wp-content\/uploads\/2025\/07\/nunziaalfonso_social-e1760637721719.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nunzioalfonso.it\\\/termini-e-condizioni\\\/\",\"url\":\"https:\\\/\\\/nunzioalfonso.it\\\/termini-e-condizioni\\\/\",\"name\":\"Termini e Condizioni - nunzioalfonso.it\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nunzioalfonso.it\\\/#website\"},\"datePublished\":\"2025-11-21T13:05:38+00:00\",\"dateModified\":\"2025-11-30T12:49:48+00:00\",\"description\":\"Leggi le condizioni generali di vendita, le modalit\u00e0 di pagamento, la garanzia e i diritti di recesso per l'acquisto su Nunzio Alfonso Srl.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nunzioalfonso.it\\\/termini-e-condizioni\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nunzioalfonso.it\\\/termini-e-condizioni\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nunzioalfonso.it\\\/termini-e-condizioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nunzioalfonso.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termini e Condizioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nunzioalfonso.it\\\/#website\",\"url\":\"https:\\\/\\\/nunzioalfonso.it\\\/\",\"name\":\"nunzioalfonso.it\",\"description\":\"Un partner unico per industria e artigianato\",\"publisher\":{\"@id\":\"https:\\\/\\\/nunzioalfonso.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nunzioalfonso.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nunzioalfonso.it\\\/#organization\",\"name\":\"Nunzio Alfonso Srl\",\"url\":\"https:\\\/\\\/nunzioalfonso.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/nunzioalfonso.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nunzioalfonso.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-icona-na-512-new-1.png\",\"contentUrl\":\"https:\\\/\\\/nunzioalfonso.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-icona-na-512-new-1.png\",\"width\":512,\"height\":512,\"caption\":\"Nunzio Alfonso Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/nunzioalfonso.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Termini e Condizioni - nunzioalfonso.it","description":"Leggi le condizioni generali di vendita, le modalit\u00e0 di pagamento, la garanzia e i diritti di recesso per l'acquisto su Nunzio Alfonso Srl.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nunzioalfonso.it\/en\/termini-e-condizioni\/","og_locale":"en_GB","og_type":"article","og_title":"Termini e Condizioni - nunzioalfonso.it","og_description":"Leggi le condizioni generali di vendita, le modalit\u00e0 di pagamento, la garanzia e i diritti di recesso per l'acquisto su Nunzio Alfonso Srl.","og_url":"https:\/\/nunzioalfonso.it\/en\/termini-e-condizioni\/","og_site_name":"nunzioalfonso.it","article_modified_time":"2025-11-30T12:49:48+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/nunzioalfonso.it\/wp-content\/uploads\/2025\/07\/nunziaalfonso_social-e1760637721719.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nunzioalfonso.it\/termini-e-condizioni\/","url":"https:\/\/nunzioalfonso.it\/termini-e-condizioni\/","name":"Termini e Condizioni - nunzioalfonso.it","isPartOf":{"@id":"https:\/\/nunzioalfonso.it\/#website"},"datePublished":"2025-11-21T13:05:38+00:00","dateModified":"2025-11-30T12:49:48+00:00","description":"Leggi le condizioni generali di vendita, le modalit\u00e0 di pagamento, la garanzia e i diritti di recesso per l'acquisto su Nunzio Alfonso Srl.","breadcrumb":{"@id":"https:\/\/nunzioalfonso.it\/termini-e-condizioni\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nunzioalfonso.it\/termini-e-condizioni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nunzioalfonso.it\/termini-e-condizioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nunzioalfonso.it\/"},{"@type":"ListItem","position":2,"name":"Termini e Condizioni"}]},{"@type":"WebSite","@id":"https:\/\/nunzioalfonso.it\/#website","url":"https:\/\/nunzioalfonso.it\/","name":"nunzioalfonso.it","description":"Un partner unico per industria e artigianato","publisher":{"@id":"https:\/\/nunzioalfonso.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nunzioalfonso.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/nunzioalfonso.it\/#organization","name":"Nunzio Alfonso Srl","url":"https:\/\/nunzioalfonso.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/nunzioalfonso.it\/#\/schema\/logo\/image\/","url":"https:\/\/nunzioalfonso.it\/wp-content\/uploads\/2025\/07\/cropped-icona-na-512-new-1.png","contentUrl":"https:\/\/nunzioalfonso.it\/wp-content\/uploads\/2025\/07\/cropped-icona-na-512-new-1.png","width":512,"height":512,"caption":"Nunzio Alfonso Srl"},"image":{"@id":"https:\/\/nunzioalfonso.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nunzioalfonso.it\/en\/wp-json\/wp\/v2\/pages\/9947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nunzioalfonso.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nunzioalfonso.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nunzioalfonso.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nunzioalfonso.it\/en\/wp-json\/wp\/v2\/comments?post=9947"}],"version-history":[{"count":5,"href":"https:\/\/nunzioalfonso.it\/en\/wp-json\/wp\/v2\/pages\/9947\/revisions"}],"predecessor-version":[{"id":10011,"href":"https:\/\/nunzioalfonso.it\/en\/wp-json\/wp\/v2\/pages\/9947\/revisions\/10011"}],"wp:attachment":[{"href":"https:\/\/nunzioalfonso.it\/en\/wp-json\/wp\/v2\/media?parent=9947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}